{"id":3254,"date":"2026-01-11T17:36:08","date_gmt":"2026-01-11T16:36:08","guid":{"rendered":"https:\/\/zingenmetzorgflevoland.nl\/?post_type=tribe_events&#038;p=3254"},"modified":"2026-01-11T17:36:08","modified_gmt":"2026-01-11T16:36:08","slug":"het-wilgenhuis-6","status":"publish","type":"tribe_events","link":"https:\/\/zingenmetzorgflevoland.nl\/index.php\/event\/het-wilgenhuis-6\/","title":{"rendered":"Het Wilgenhuis"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-3254","tribe_events","type-tribe_events","status-publish","hentry"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/zingenmetzorgflevoland.nl\/index.php\/wp-json\/wp\/v2\/tribe_events\/3254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zingenmetzorgflevoland.nl\/index.php\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/zingenmetzorgflevoland.nl\/index.php\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/zingenmetzorgflevoland.nl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/zingenmetzorgflevoland.nl\/index.php\/wp-json\/wp\/v2\/tribe_events\/3254\/revisions"}],"predecessor-version":[{"id":3255,"href":"https:\/\/zingenmetzorgflevoland.nl\/index.php\/wp-json\/wp\/v2\/tribe_events\/3254\/revisions\/3255"}],"wp:attachment":[{"href":"https:\/\/zingenmetzorgflevoland.nl\/index.php\/wp-json\/wp\/v2\/media?parent=3254"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zingenmetzorgflevoland.nl\/index.php\/wp-json\/wp\/v2\/tags?post=3254"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/zingenmetzorgflevoland.nl\/index.php\/wp-json\/wp\/v2\/tribe_events_cat?post=3254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}